{"id":295,"date":"2022-07-30T14:49:44","date_gmt":"2022-07-30T14:49:44","guid":{"rendered":"http:\/\/localhost\/photogallery\/?page_id=295"},"modified":"2024-11-25T19:27:54","modified_gmt":"2024-11-25T19:27:54","slug":"cuba-libre","status":"publish","type":"page","link":"https:\/\/saskiacloosterman.nl\/photogallery\/cuba-libre\/","title":{"rendered":"Cuba Libre"},"content":{"rendered":"Lagrimas Negras &#8211; Cuba Feliz y Libre <div class=\"sc_fancy_player_container\"><audio class=\"wp-audio-shortcode\" id=\"audio-295-1\" loop autoplay preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/09\/Lagrimas-Negras-Cuba-feliz-y-libre.mp3?_=1\" \/><a href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/09\/Lagrimas-Negras-Cuba-feliz-y-libre.mp3\">https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/09\/Lagrimas-Negras-Cuba-feliz-y-libre.mp3<\/a><\/audio><\/div>\r\n<div id=\"grid-gallery-16-98028\" data-gg-id=\"16\" data-title=\"Cuba Libre\" data-grid-type=\"1\" data-offset=\"4.3\" data-area-position=\"center\" data-icons=\"false\" data-preloader=\"true\" data-width=\"30%\" data-height=\"\" data-padding=\"4\" data-quicksand=\"disabled\" data-quicksand-duration=\"none\" data-popup-theme=\"theme_7\" data-popup-type=\"colorbox\" data-popup-fadeOut=\"300\" data-popup-captions=\"hide\" data-popup-image-text=\"data-description\" data-popup-widthsize=\"auto\" data-popup-heightsize=\"auto\" data-popup-i18n-words=\"{&quot;close&quot;:&quot;close&quot;,&quot;next&quot;:&quot;next&quot;,&quot;previous&quot;:&quot;previous&quot;,&quot;start_slideshow&quot;:&quot;start slideshow&quot;,&quot;stop_slideshow&quot;:&quot;stop slideshow&quot;,&quot;image&quot;:&quot;image&quot;,&quot;of&quot;:&quot;of&quot;,&quot;prev&quot;:&quot;prev&quot;,&quot;cExpand&quot;:&quot;Expand&quot;,&quot;cPrevious&quot;:&quot;Previous&quot;,&quot;cNext&quot;:&quot;Next&quot;,&quot;cExpandStr&quot;:&quot;Expand the image&quot;,&quot;cRotate&quot;:&quot;Rotate&quot;,&quot;cDetails&quot;:&quot;Details&quot;}\" data-popup-slideshow=\"true\" data-popup-slideshow-speed=\"2500\" data-popup-hoverstop=\"true\" data-popup-slideshow-auto=\"false\" data-popup-background=\"#000000\" data-popup-transparency=\"30\" data-popup-disable-history=\"\" data-popup-disable-changed-url=\"\" data-popup-border-type=\"solid\" data-popup-border-color=\"\" data-popup-border-width=\"\" data-popup-border-enable=\"\" data-fullscreen=\"false\" data-hide-tooltip=\"false\" data-caption-font-family=\"Default\" data-caption-text-size=\"14px\" data-is-mobile=\"0\" data-caption-mobile=\"false\" data-hide-long-tltp-title=\"1\" data-caption-disabled-on-mobile=\"false\" data-popup-placement-type=\"0\" data-social-sharing=\"{&quot;enabled&quot;:&quot;&quot;,&quot;gallerySharing&quot;:{&quot;enabled&quot;:null,&quot;position&quot;:null},&quot;imageSharing&quot;:{&quot;enabled&quot;:null,&quot;wrapperClass&quot;:&quot; vertical &quot;},&quot;popupSharing&quot;:{&quot;enabled&quot;:null,&quot;wrapperClass&quot;:&quot; vertical &quot;}}\" class=\"grid-gallery grid-gallery-fluid-height \" style=\" width:100%; height:auto; margin-left:auto; margin-right:auto;position:relative;\"> <div class=\"gallery-loading\"> <div class=\"blocks\"> <div class=\"block\"><\/div> <div class=\"block\"><\/div> <div class=\"block\"><\/div> <div class=\"block\"><\/div> <\/div> <\/div> <div class=\"gallery-sharing-top\"><\/div> <div id=\"photos-16\" class=\"grid-gallery-photos\"><a id=\"gg-16-319\" class=\"gg-link gg-colorbox\" data-attachment-id=\"46\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-01.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"0\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-01.jpg\" class=\"ggImg\" alt=\"CUBA-01\" data-description=\"CUBA-01\" data-caption=\"CUBA-01\" data-title=\"CUBA-01\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-320\" class=\"gg-link gg-colorbox\" data-attachment-id=\"45\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-29.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"1\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-29.jpg\" class=\"ggImg\" alt=\"CUBA-29\" data-description=\"CUBA-29\" data-caption=\"CUBA-29\" data-title=\"CUBA-29\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-321\" class=\"gg-link gg-colorbox\" data-attachment-id=\"44\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-28.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"2\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-28.jpg\" class=\"ggImg\" alt=\"CUBA-28\" data-description=\"CUBA-28\" data-caption=\"CUBA-28\" data-title=\"CUBA-28\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-322\" class=\"gg-link gg-colorbox\" data-attachment-id=\"43\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-27.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"3\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-27.jpg\" class=\"ggImg\" alt=\"CUBA-27\" data-description=\"CUBA-27\" data-caption=\"CUBA-27\" data-title=\"CUBA-27\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-323\" class=\"gg-link gg-colorbox\" data-attachment-id=\"42\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-26.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"4\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-26.jpg\" class=\"ggImg\" alt=\"CUBA-26\" data-description=\"CUBA-26\" data-caption=\"CUBA-26\" data-title=\"CUBA-26\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-324\" class=\"gg-link gg-colorbox\" data-attachment-id=\"40\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-24.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"5\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-24.jpg\" class=\"ggImg\" alt=\"CUBA-24\" data-description=\"CUBA-24\" data-caption=\"CUBA-24\" data-title=\"CUBA-24\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-325\" class=\"gg-link gg-colorbox\" data-attachment-id=\"41\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-25.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"6\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-25.jpg\" class=\"ggImg\" alt=\"CUBA-25\" data-description=\"CUBA-25\" data-caption=\"CUBA-25\" data-title=\"CUBA-25\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-326\" class=\"gg-link gg-colorbox\" data-attachment-id=\"39\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-23.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"7\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-23.jpg\" class=\"ggImg\" alt=\"CUBA-23\" data-description=\"CUBA-23\" data-caption=\"CUBA-23\" data-title=\"CUBA-23\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-327\" class=\"gg-link gg-colorbox\" data-attachment-id=\"38\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-22.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"8\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-22.jpg\" class=\"ggImg\" alt=\"CUBA-22\" data-description=\"CUBA-22\" data-caption=\"CUBA-22\" data-title=\"CUBA-22\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-328\" class=\"gg-link gg-colorbox\" data-attachment-id=\"36\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-20.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"9\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-20.jpg\" class=\"ggImg\" alt=\"CUBA-20\" data-description=\"CUBA-20\" data-caption=\"CUBA-20\" data-title=\"CUBA-20\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-329\" class=\"gg-link gg-colorbox\" data-attachment-id=\"37\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-21.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"10\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-21.jpg\" class=\"ggImg\" alt=\"CUBA-21\" data-description=\"CUBA-21\" data-caption=\"CUBA-21\" data-title=\"CUBA-21\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-330\" class=\"gg-link gg-colorbox\" data-attachment-id=\"35\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-19.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"11\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-19.jpg\" class=\"ggImg\" alt=\"CUBA-19\" data-description=\"CUBA-19\" data-caption=\"CUBA-19\" data-title=\"CUBA-19\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-331\" class=\"gg-link gg-colorbox\" data-attachment-id=\"33\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-17.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"12\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-17.jpg\" class=\"ggImg\" alt=\"CUBA-17\" data-description=\"CUBA-17\" data-caption=\"CUBA-17\" data-title=\"CUBA-17\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-332\" class=\"gg-link gg-colorbox\" data-attachment-id=\"34\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-18.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"13\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-18.jpg\" class=\"ggImg\" alt=\"CUBA-18\" data-description=\"CUBA-18\" data-caption=\"CUBA-18\" data-title=\"CUBA-18\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-333\" class=\"gg-link gg-colorbox\" data-attachment-id=\"32\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-15.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"14\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-15.jpg\" class=\"ggImg\" alt=\"CUBA-15\" data-description=\"CUBA-15\" data-caption=\"CUBA-15\" data-title=\"CUBA-15\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-334\" class=\"gg-link gg-colorbox\" data-attachment-id=\"31\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-14.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"15\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-14.jpg\" class=\"ggImg\" alt=\"CUBA-14\" data-description=\"CUBA-14\" data-caption=\"CUBA-14\" data-title=\"CUBA-14\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-335\" class=\"gg-link gg-colorbox\" data-attachment-id=\"29\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-11.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"16\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-11.jpg\" class=\"ggImg\" alt=\"CUBA-11\" data-description=\"CUBA-11\" data-caption=\"CUBA-11\" data-title=\"CUBA-11\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-336\" class=\"gg-link gg-colorbox\" data-attachment-id=\"30\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-12.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"17\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-12.jpg\" class=\"ggImg\" alt=\"CUBA-12\" data-description=\"CUBA-12\" data-caption=\"CUBA-12\" data-title=\"CUBA-12\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-337\" class=\"gg-link gg-colorbox\" data-attachment-id=\"27\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-09.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"18\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-09.jpg\" class=\"ggImg\" alt=\"CUBA-09\" data-description=\"CUBA-09\" data-caption=\"CUBA-09\" data-title=\"CUBA-09\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-338\" class=\"gg-link gg-colorbox\" data-attachment-id=\"28\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-10.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"19\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-10.jpg\" class=\"ggImg\" alt=\"CUBA-10\" data-description=\"CUBA-10\" data-caption=\"CUBA-10\" data-title=\"CUBA-10\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-339\" class=\"gg-link gg-colorbox\" data-attachment-id=\"25\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-07.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"20\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-07.jpg\" class=\"ggImg\" alt=\"CUBA-07\" data-description=\"CUBA-07\" data-caption=\"CUBA-07\" data-title=\"CUBA-07\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-340\" class=\"gg-link gg-colorbox\" data-attachment-id=\"26\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-08.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"21\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-08.jpg\" class=\"ggImg\" alt=\"CUBA-08\" data-description=\"CUBA-08\" data-caption=\"CUBA-08\" data-title=\"CUBA-08\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-341\" class=\"gg-link gg-colorbox\" data-attachment-id=\"23\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-05.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"22\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-05.jpg\" class=\"ggImg\" alt=\"CUBA-05\" data-description=\"CUBA-05\" data-caption=\"CUBA-05\" data-title=\"CUBA-05\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-342\" class=\"gg-link gg-colorbox\" data-attachment-id=\"24\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-06.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"23\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-06.jpg\" class=\"ggImg\" alt=\"CUBA-06\" data-description=\"CUBA-06\" data-caption=\"CUBA-06\" data-title=\"CUBA-06\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-343\" class=\"gg-link gg-colorbox\" data-attachment-id=\"22\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-04.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"24\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-04.jpg\" class=\"ggImg\" alt=\"CUBA-04\" data-description=\"CUBA-04\" data-caption=\"CUBA-04\" data-title=\"CUBA-04\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a><a id=\"gg-16-344\" class=\"gg-link gg-colorbox\" data-attachment-id=\"20\" href=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-02.jpg?gid=16\" target=\"_self\" rel=\"\" style=\"border-radius:0%;\" ><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"25\" style=\"display:none;border-radius:0%;; margin:4.3px; width:30%;\" ><div class=\"crop\" style=\"\"><img decoding=\"async\" src=\"https:\/\/saskiacloosterman.nl\/photogallery\/wp-content\/uploads\/2022\/07\/CUBA-02.jpg\" class=\"ggImg\" alt=\"CUBA-02\" data-description=\"CUBA-02\" data-caption=\"CUBA-02\" data-title=\"CUBA-02\" style=\"\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:14px; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\" vertical-align:top;\"><\/div><\/FIGCAPTION><\/FIGURE><\/a> <div class=\"grid-gallery-clearfix\"><\/div> <\/div> <div class=\"gallery-sharing-bottom\"><\/div> <div class=\"grid-gallery-clearfix\"><\/div> <\/div> <!-- Gallery by Supsystic plugin1.15.12 -->\n","protected":false},"excerpt":{"rendered":"<p>Lagrimas Negras &#8211; Cuba Feliz y Libre<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-295","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/saskiacloosterman.nl\/photogallery\/wp-json\/wp\/v2\/pages\/295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saskiacloosterman.nl\/photogallery\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/saskiacloosterman.nl\/photogallery\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/saskiacloosterman.nl\/photogallery\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saskiacloosterman.nl\/photogallery\/wp-json\/wp\/v2\/comments?post=295"}],"version-history":[{"count":7,"href":"https:\/\/saskiacloosterman.nl\/photogallery\/wp-json\/wp\/v2\/pages\/295\/revisions"}],"predecessor-version":[{"id":429,"href":"https:\/\/saskiacloosterman.nl\/photogallery\/wp-json\/wp\/v2\/pages\/295\/revisions\/429"}],"wp:attachment":[{"href":"https:\/\/saskiacloosterman.nl\/photogallery\/wp-json\/wp\/v2\/media?parent=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}